{"id":389,"date":"2023-03-26T14:00:44","date_gmt":"2023-03-26T05:00:44","guid":{"rendered":"http:\/\/www.doc-shibaura.com\/blog-doc\/?p=389"},"modified":"2023-03-26T14:00:44","modified_gmt":"2023-03-26T05:00:44","slug":"%ef%bc%94%e6%9c%88%e3%81%ae%e8%a8%ba%e7%99%82%e6%97%a5%e7%a8%8b","status":"publish","type":"post","link":"https:\/\/www.doc-shibaura.com\/blog-doc\/archives\/389","title":{"rendered":"\uff14\u6708\u306e\u8a3a\u7642\u65e5\u7a0b"},"content":{"rendered":"<p>GW\u306f4\/29\u30fb5\/3\uff5e5\/5\u304c\u795d\u65e5\u306e\u305f\u3081\u4f11\u8a3a\u3068\u306a\u308a\u307e\u3059\u3002<img loading=\"lazy\" class=\"alignright size-full wp-image-386\" src=\"http:\/\/www.doc-shibaura.com\/blog-doc\/wp-content\/uploads\/2023\/03\/202304.png\" alt=\"\" width=\"982\" height=\"688\" srcset=\"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-content\/uploads\/2023\/03\/202304.png 982w, https:\/\/www.doc-shibaura.com\/blog-doc\/wp-content\/uploads\/2023\/03\/202304-300x210.png 300w, https:\/\/www.doc-shibaura.com\/blog-doc\/wp-content\/uploads\/2023\/03\/202304-768x538.png 768w\" sizes=\"(max-width: 982px) 100vw, 982px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GW\u306f4\/29\u30fb5\/3\uff5e5\/5\u304c\u795d\u65e5\u306e\u305f\u3081\u4f11\u8a3a\u3068\u306a\u308a\u307e\u3059\u3002<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/posts\/389"}],"collection":[{"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/comments?post=389"}],"version-history":[{"count":1,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/posts\/389\/revisions"}],"predecessor-version":[{"id":390,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/posts\/389\/revisions\/390"}],"wp:attachment":[{"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/media?parent=389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/categories?post=389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doc-shibaura.com\/blog-doc\/wp-json\/wp\/v2\/tags?post=389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}